{"id":1496,"date":"2017-06-15T14:31:32","date_gmt":"2017-06-15T06:31:32","guid":{"rendered":"https:\/\/sellgoldmalaysia.com\/?p=1496"},"modified":"2017-06-15T14:31:32","modified_gmt":"2017-06-15T06:31:32","slug":"who-controls-all-of-our-money","status":"publish","type":"post","link":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/","title":{"rendered":"Who Controls All of Our Money?"},"content":{"rendered":"<p>15 June 2017<\/p>\n<p>from <a href=\"https:\/\/www.youtube.com\/channel\/UC4QZ_LsYcvcq7qOsOhpAX4A\" target=\"_blank\">ColdFusion<\/a>:<\/p>\n<div class=\"videoWrapperOuter\">\n<div class=\"videoWrapperInner\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/mQUhJTxK5mA\" frameborder=\"0\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Most people\u2019s lives are dedicated to money. It\u2019s all people ever worry about or talk about. People train to learn the skills to get jobs to trade hours of their lives for money. But where does money come from? And who controls it? This 21-minute video from <a href=\"https:\/\/www.youtube.com\/channel\/UC4QZ_LsYcvcq7qOsOhpAX4A\" target=\"_blank\">ColdFusion<\/a> explains it all.<\/p>","protected":false},"excerpt":{"rendered":"<p>15 June 2017 from ColdFusion: Most people\u2019s lives are dedicated to money. It\u2019s all people ever worry about or talk about. People train to learn the skills to get jobs to trade hours of their lives for money. But where does money come from? And who controls it? This 21-minute video from ColdFusion explains it&hellip;&nbsp;<a href=\"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Who Controls All of Our Money?<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":1278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[21,14],"tags":[],"class_list":["post-1496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economic-collapse","category-economy"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dean Arif\"\/>\n\t<meta name=\"google-site-verification\" content=\"0OOvU1BWdmkHagP16vkboPrUNCtFK7M3YM4SLEcFLK8\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ms_MY\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Sell Gold Malaysia | Sell Gold &amp; Silver Best Price in Malaysia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Who Controls All of Our Money? | Sell Gold Malaysia\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/sellgoldmalaysia-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/sellgoldmalaysia-logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-15T06:31:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-06-15T06:31:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Who Controls All of Our Money? | Sell Gold Malaysia\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/sellgoldmalaysia-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#article\",\"name\":\"Who Controls All of Our Money? | Sell Gold Malaysia\",\"headline\":\"Who Controls All of Our Money?\",\"author\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/author\\\/deanarif\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/wealth-inequality.jpg\",\"width\":800,\"height\":400},\"datePublished\":\"2017-06-15T14:31:32+08:00\",\"dateModified\":\"2017-06-15T14:31:32+08:00\",\"inLanguage\":\"ms-MY\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#webpage\"},\"articleSection\":\"Economic Collapse, Economy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/category\\\/economy\\\/#listItem\",\"name\":\"Economy\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/category\\\/economy\\\/#listItem\",\"position\":2,\"name\":\"Economy\",\"item\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/category\\\/economy\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#listItem\",\"name\":\"Who Controls All of Our Money?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#listItem\",\"position\":3,\"name\":\"Who Controls All of Our Money?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/category\\\/economy\\\/#listItem\",\"name\":\"Economy\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/#organization\",\"name\":\"Sell Gold Malaysia\",\"description\":\"Sell Gold & Silver Best Price in Malaysia\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/\",\"telephone\":\"+60172283278\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/SGM-icon.png\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#organizationLogo\",\"width\":50,\"height\":45},\"image\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/author\\\/deanarif\\\/#author\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/author\\\/deanarif\\\/\",\"name\":\"Dean Arif\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb3917634ae32637931d61dc6a18a6ac4d564353b955de14d5ee55fd3a7896e8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dean Arif\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#webpage\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/\",\"name\":\"Who Controls All of Our Money? | Sell Gold Malaysia\",\"inLanguage\":\"ms-MY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/author\\\/deanarif\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/author\\\/deanarif\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/wealth-inequality.jpg\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#mainImage\",\"width\":800,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/who-controls-all-of-our-money\\\/#mainImage\"},\"datePublished\":\"2017-06-15T14:31:32+08:00\",\"dateModified\":\"2017-06-15T14:31:32+08:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/#website\",\"url\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/\",\"name\":\"Sell Gold Malaysia\",\"alternateName\":\"Sell Gold Best Rate in Malaysia\",\"description\":\"Sell Gold & Silver Best Price in Malaysia\",\"inLanguage\":\"ms-MY\",\"publisher\":{\"@id\":\"https:\\\/\\\/sellgoldmalaysia.com\\\/bm\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Who Controls All of Our Money? | Sell Gold Malaysia","description":"","canonical_url":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"0OOvU1BWdmkHagP16vkboPrUNCtFK7M3YM4SLEcFLK8","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#article","name":"Who Controls All of Our Money? | Sell Gold Malaysia","headline":"Who Controls All of Our Money?","author":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/author\/deanarif\/#author"},"publisher":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2017\/03\/wealth-inequality.jpg","width":800,"height":400},"datePublished":"2017-06-15T14:31:32+08:00","dateModified":"2017-06-15T14:31:32+08:00","inLanguage":"ms-MY","mainEntityOfPage":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#webpage"},"isPartOf":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#webpage"},"articleSection":"Economic Collapse, Economy"},{"@type":"BreadcrumbList","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm#listItem","position":1,"name":"Home","item":"https:\/\/sellgoldmalaysia.com\/bm","nextItem":{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm\/category\/economy\/#listItem","name":"Economy"}},{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm\/category\/economy\/#listItem","position":2,"name":"Economy","item":"https:\/\/sellgoldmalaysia.com\/bm\/category\/economy\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#listItem","name":"Who Controls All of Our Money?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#listItem","position":3,"name":"Who Controls All of Our Money?","previousItem":{"@type":"ListItem","@id":"https:\/\/sellgoldmalaysia.com\/bm\/category\/economy\/#listItem","name":"Economy"}}]},{"@type":"Organization","@id":"https:\/\/sellgoldmalaysia.com\/bm\/#organization","name":"Sell Gold Malaysia","description":"Sell Gold & Silver Best Price in Malaysia","url":"https:\/\/sellgoldmalaysia.com\/bm\/","telephone":"+60172283278","logo":{"@type":"ImageObject","url":"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/SGM-icon.png","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#organizationLogo","width":50,"height":45},"image":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/sellgoldmalaysia.com\/bm\/author\/deanarif\/#author","url":"https:\/\/sellgoldmalaysia.com\/bm\/author\/deanarif\/","name":"Dean Arif","image":{"@type":"ImageObject","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/eb3917634ae32637931d61dc6a18a6ac4d564353b955de14d5ee55fd3a7896e8?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dean Arif"}},{"@type":"WebPage","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#webpage","url":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/","name":"Who Controls All of Our Money? | Sell Gold Malaysia","inLanguage":"ms-MY","isPartOf":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/#website"},"breadcrumb":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#breadcrumblist"},"author":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/author\/deanarif\/#author"},"creator":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/author\/deanarif\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2017\/03\/wealth-inequality.jpg","@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#mainImage","width":800,"height":400},"primaryImageOfPage":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/#mainImage"},"datePublished":"2017-06-15T14:31:32+08:00","dateModified":"2017-06-15T14:31:32+08:00"},{"@type":"WebSite","@id":"https:\/\/sellgoldmalaysia.com\/bm\/#website","url":"https:\/\/sellgoldmalaysia.com\/bm\/","name":"Sell Gold Malaysia","alternateName":"Sell Gold Best Rate in Malaysia","description":"Sell Gold & Silver Best Price in Malaysia","inLanguage":"ms-MY","publisher":{"@id":"https:\/\/sellgoldmalaysia.com\/bm\/#organization"}}]},"og:locale":"ms_MY","og:site_name":"Sell Gold Malaysia | Sell Gold &amp; Silver Best Price in Malaysia","og:type":"article","og:title":"Who Controls All of Our Money? | Sell Gold Malaysia","og:url":"https:\/\/sellgoldmalaysia.com\/bm\/who-controls-all-of-our-money\/","og:image":"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/sellgoldmalaysia-logo.png","og:image:secure_url":"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/sellgoldmalaysia-logo.png","article:published_time":"2017-06-15T06:31:32+00:00","article:modified_time":"2017-06-15T06:31:32+00:00","twitter:card":"summary","twitter:title":"Who Controls All of Our Money? | Sell Gold Malaysia","twitter:image":"https:\/\/sellgoldmalaysia.com\/wp-content\/uploads\/2019\/10\/sellgoldmalaysia-logo.png"},"aioseo_meta_data":{"post_id":"1496","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 06:34:12","updated":"2025-06-03 19:09:31","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/posts\/1496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/comments?post=1496"}],"version-history":[{"count":0,"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/posts\/1496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/media\/1278"}],"wp:attachment":[{"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/media?parent=1496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/categories?post=1496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sellgoldmalaysia.com\/bm\/wp-json\/wp\/v2\/tags?post=1496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}